{"id":18327,"date":"2024-03-13T00:18:28","date_gmt":"2024-03-12T23:18:28","guid":{"rendered":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/?p=18327"},"modified":"2024-03-13T00:18:29","modified_gmt":"2024-03-12T23:18:29","slug":"um-den-alptraum-des-globalen-pandemievertrags-zu-stoppen-bleiben-nur-noch-tage","status":"publish","type":"post","link":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/2024\/03\/13\/um-den-alptraum-des-globalen-pandemievertrags-zu-stoppen-bleiben-nur-noch-tage\/","title":{"rendered":"UM DEN ALPTRAUM DES GLOBALEN PANDEMIEVERTRAGS ZU STOPPEN, BLEIBEN NUR NOCH TAGE"},"content":{"rendered":"\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-ansage wp-block-embed-ansage\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"25Hawqc2KI\"><a href=\"https:\/\/ansage.org\/um-den-alptraum-des-globalen-pandemievertrags-zu-stoppen-bleiben-nur-noch-tage\/\">Um den Alptraum des globalen Pandemievertrags zu stoppen, bleiben nur noch Tage<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8222;Um den Alptraum des globalen Pandemievertrags zu stoppen, bleiben nur noch Tage&#8220; &#8212; Ansage\" src=\"https:\/\/ansage.org\/um-den-alptraum-des-globalen-pandemievertrags-zu-stoppen-bleiben-nur-noch-tage\/embed\/#?secret=4FgF1jSST8#?secret=25Hawqc2KI\" data-secret=\"25Hawqc2KI\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-18327","post","type-post","status-publish","format-standard","hentry","category-allgemein","entry"],"_links":{"self":[{"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/posts\/18327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/comments?post=18327"}],"version-history":[{"count":1,"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/posts\/18327\/revisions"}],"predecessor-version":[{"id":18328,"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/posts\/18327\/revisions\/18328"}],"wp:attachment":[{"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/media?parent=18327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/categories?post=18327"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/tags?post=18327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}