{"id":18337,"date":"2024-03-14T18:16:37","date_gmt":"2024-03-14T17:16:37","guid":{"rendered":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/?p=18337"},"modified":"2024-03-14T18:16:38","modified_gmt":"2024-03-14T17:16:38","slug":"mitten-im-unterricht-schuelerin-festgenommen-wegen-internet-posts","status":"publish","type":"post","link":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/2024\/03\/14\/mitten-im-unterricht-schuelerin-festgenommen-wegen-internet-posts\/","title":{"rendered":"Mitten im Unterricht: Sch\u00fclerin festgenommen wegen Internet-Posts"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Sie schrieb auf TikTok, dass Deutschland nicht nur ein Ort, sondern Heimat ist<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/reitschuster.de\/post\/mitten-im-unterricht-schuelerin-festgenommen-wegen-internet-posts\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/reitschuster.de\/post\/mitten-im-unterricht-schuelerin-festgenommen-wegen-internet-posts\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sie schrieb auf TikTok, dass Deutschland nicht nur ein Ort, sondern Heimat ist https:\/\/reitschuster.de\/post\/mitten-im-unterricht-schuelerin-festgenommen-wegen-internet-posts\/<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-18337","post","type-post","status-publish","format-standard","hentry","category-allgemein","entry"],"_links":{"self":[{"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/posts\/18337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/comments?post=18337"}],"version-history":[{"count":1,"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/posts\/18337\/revisions"}],"predecessor-version":[{"id":18338,"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/posts\/18337\/revisions\/18338"}],"wp:attachment":[{"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/media?parent=18337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/categories?post=18337"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/tags?post=18337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}