{"id":18358,"date":"2024-03-24T16:25:30","date_gmt":"2024-03-24T15:25:30","guid":{"rendered":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/?p=18358"},"modified":"2024-03-24T16:26:00","modified_gmt":"2024-03-24T15:26:00","slug":"18358","status":"publish","type":"post","link":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/2024\/03\/24\/18358\/","title":{"rendered":"Neue Studie belegt Anstieg von Krebserkrankungen und Todesf\u00e4llen ab 2021 bei jungen Menschen"},"content":{"rendered":"\n<p><a href=\"https:\/\/www.alexander-wallasch.de\/gesellschaft\/neue-studie-belegt-anstieg-von-krebserkrankungen-und-todesfaellen-ab-2021-bei-jungen-menschen\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.alexander-wallasch.de\/gesellschaft\/neue-studie-belegt-anstieg-von-krebserkrankungen-und-todesfaellen-ab-2021-bei-jungen-menschen<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>https:\/\/www.alexander-wallasch.de\/gesellschaft\/neue-studie-belegt-anstieg-von-krebserkrankungen-und-todesfaellen-ab-2021-bei-jungen-menschen<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-18358","post","type-post","status-publish","format-standard","hentry","category-allgemein","entry"],"_links":{"self":[{"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/posts\/18358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/comments?post=18358"}],"version-history":[{"count":2,"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/posts\/18358\/revisions"}],"predecessor-version":[{"id":18360,"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/posts\/18358\/revisions\/18360"}],"wp:attachment":[{"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/media?parent=18358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/categories?post=18358"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/tags?post=18358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}