{"id":3785,"date":"2020-06-14T10:45:03","date_gmt":"2020-06-14T08:45:03","guid":{"rendered":"http:\/\/qanon.at\/?p=3785"},"modified":"2020-06-14T10:45:03","modified_gmt":"2020-06-14T08:45:03","slug":"samuel-eckert-bundesamt-fuer-statistik-update-statement-von-italiens-beruehmtestem-arzt-corona-ist-vergangenheit","status":"publish","type":"post","link":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/2020\/06\/14\/samuel-eckert-bundesamt-fuer-statistik-update-statement-von-italiens-beruehmtestem-arzt-corona-ist-vergangenheit\/","title":{"rendered":"SAMUEL ECKERT: Bundesamt f\u00fcr Statistik UPDATE! Statement von Italiens ber\u00fchmtestem Arzt: Corona ist VERGANGENHEIT!"},"content":{"rendered":"\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/m.youtube.com\/watch?v=ess22_LatuA\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3785","post","type-post","status-publish","format-standard","hentry","category-allgemein","entry"],"_links":{"self":[{"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/posts\/3785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/comments?post=3785"}],"version-history":[{"count":0,"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/posts\/3785\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/media?parent=3785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/categories?post=3785"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/tags?post=3785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}