{"id":5451,"date":"2020-08-11T11:27:47","date_gmt":"2020-08-11T09:27:47","guid":{"rendered":"http:\/\/qanon.at\/?p=5451"},"modified":"2020-08-11T11:27:47","modified_gmt":"2020-08-11T09:27:47","slug":"dwn-grosse-verwirrung-in-washington-russland-dossier-gegen-trump-war-eine-luege","status":"publish","type":"post","link":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/2020\/08\/11\/dwn-grosse-verwirrung-in-washington-russland-dossier-gegen-trump-war-eine-luege\/","title":{"rendered":"DWN \u2013 Gro\u00dfe Verwirrung in Washington: Russland-Dossier gegen Trump war eine L\u00fcge"},"content":{"rendered":"\n<p><a href=\"https:\/\/deutsche-wirtschafts-nachrichten.de\/505701\/Grosse-Verwirrung-in-Washington-Russland-Dossier-gegen-Trump-war-eine-Luege\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/deutsche-wirtschafts-nachrichten.de\/505701\/Grosse-Verwirrung-in-Washington-Russland-Dossier-gegen-Trump-war-eine-Luege<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>https:\/\/deutsche-wirtschafts-nachrichten.de\/505701\/Grosse-Verwirrung-in-Washington-Russland-Dossier-gegen-Trump-war-eine-Luege<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5451","post","type-post","status-publish","format-standard","hentry","category-allgemein","entry"],"_links":{"self":[{"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/posts\/5451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/comments?post=5451"}],"version-history":[{"count":0,"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/posts\/5451\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/media?parent=5451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/categories?post=5451"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.millionen-fliegen-fressen-scheisse.de\/wordpress\/wp-json\/wp\/v2\/tags?post=5451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}